{"id":11144,"date":"2026-07-11T09:00:00","date_gmt":"2026-07-11T07:00:00","guid":{"rendered":"https:\/\/www.cma-hautsdefrance.fr\/blog\/?p=11144"},"modified":"2026-07-10T10:39:01","modified_gmt":"2026-07-10T08:39:01","slug":"raphael-perrier-ambassadeur-de-la-coiffure-francaise-la-signature-de-lexcellence","status":"publish","type":"post","link":"https:\/\/www.cma-hautsdefrance.fr\/blog\/actualites\/raphael-perrier-ambassadeur-de-la-coiffure-francaise-la-signature-de-lexcellence\/","title":{"rendered":"Rapha\u00ebl Perrier, ambassadeur de la coiffure fran\u00e7aise : la signature de l\u2019excellence"},"content":{"rendered":"<span class=\"span-reading-time rt-reading-time\" style=\"display: block;\"><span class=\"rt-label rt-prefix\">Temps de lecture\u00a0: <\/span> <span class=\"rt-time\"> 8<\/span> <span class=\"rt-label rt-postfix\">minutes<\/span><\/span>\n<p class=\"has-medium-font-size wp-block-paragraph\"><strong>Si son visage est moins connu du grand public, son nom est une v\u00e9ritable r\u00e9f\u00e9rence dans l\u2019univers de la coiffure. H\u00e9ritier d\u2019une lign\u00e9e de coiffeurs, Rapha\u00ebl Perrier a, tr\u00e8s t\u00f4t, fait de sa passion une vocation, avant que son talent ne le propulse sur les plus grandes sc\u00e8nes internationales. Multi-titr\u00e9, il signe les coiffures de c\u00e9l\u00e9brit\u00e9s telles que Natalie Portman ou encore Johnny Depp, accompagne les sportifs des Jeux olympiques de Paris 2024, les mannequins des d\u00e9fil\u00e9s de haute couture, les artistes des com\u00e9dies musicales, tout en faisant rayonner l\u2019excellence de la coiffure fran\u00e7aise \u00e0 travers le monde lors de shows spectaculaires, de Las Vegas \u00e0 P\u00e9kin en passant par Paris. Cr\u00e9atif, exigeant et visionnaire, ce jeune quadrag\u00e9naire au look de rock star a construit un parcours unique qui conjugue savoir-faire, innovation et transmission. Toujours d\u00e9sireux de partager son exp\u00e9rience avec les nouvelles g\u00e9n\u00e9rations, il a r\u00e9cemment fait \u00e9tape \u00e0 la CMA Hauts-de-France, \u00e0 Lille, dans le cadre de son Hair Tour, pour animer deux masterclass d\u2019exception destin\u00e9es aux apprentis comme aux professionnels, en collaboration avec la CMA HDF et l&rsquo;UNEC HDF. \u00c0 cette occasion, Rapha\u00ebl Perrier est revenu sur son parcours hors norme, son engagement en faveur de la formation et sa vision d\u2019un m\u00e9tier en perp\u00e9tuelle \u00e9volution. Une rencontre inspirante et \u2026 d\u00e9coiffante avec un artisan passionn\u00e9 qui n\u2019a jamais cess\u00e9 de viser l\u2019excellence.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"font-size:14px\"><strong>-Vous \u00eates issu d\u2019une famille d\u2019artisans coiffeurs depuis trois g\u00e9n\u00e9rations. Que repr\u00e9sente cet h\u00e9ritage pour vous aujourd\u2019hui ?<br>-Raphael Perrier<\/strong>\u00a0: Cela repr\u00e9sente de la fiert\u00e9, j\u2019ai beaucoup de chance d\u2019\u00eatre issu d\u2019une famille d\u2019artisans, coiffeurs d\u2019un c\u00f4t\u00e9, p\u00e2tissiers boulangers de l\u2019autre (sourire). J\u2019ai beaucoup h\u00e9sit\u00e9 car j&rsquo;adorais la p\u00e2tisserie. Ce sont mes grands-p\u00e8res qui m\u2019ont permis de me d\u00e9cider. J\u2019aimais toutes les d\u00e9corations en sucre et mon grand-p\u00e8re p\u00e2tissier m\u2019a dit que ce n\u2019\u00e9tait pas cela la p\u00e2tisserie en r\u00e9alit\u00e9, c\u2019\u00e9tait juste ce que l\u2019on voit dans les concours. Il m\u2019a un peu d\u00e9courag\u00e9 je l\u2019avoue (rire) et puis je passais plus de temps du coup dans le salon de coiffure de mon p\u00e8re. J\u2019avais 5 ans, j\u2019adorais d\u00e9j\u00e0 ce contact qu\u2019il avait avec les gens. Il les rendait beaux aussi. Le choix s\u2019est fait comme \u00e7a. Je suis content de cet h\u00e9ritage familial.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"alignleft size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/www.cma-hautsdefrance.fr\/blog\/wp-content\/uploads\/2026\/07\/IMG_1753-768x1024.jpeg\" alt=\"\" class=\"wp-image-11156\" style=\"width:350px;height:auto\" srcset=\"https:\/\/www.cma-hautsdefrance.fr\/blog\/wp-content\/uploads\/2026\/07\/IMG_1753-768x1024.jpeg 768w, https:\/\/www.cma-hautsdefrance.fr\/blog\/wp-content\/uploads\/2026\/07\/IMG_1753-225x300.jpeg 225w, https:\/\/www.cma-hautsdefrance.fr\/blog\/wp-content\/uploads\/2026\/07\/IMG_1753-1152x1536.jpeg 1152w, https:\/\/www.cma-hautsdefrance.fr\/blog\/wp-content\/uploads\/2026\/07\/IMG_1753-1536x2048.jpeg 1536w, https:\/\/www.cma-hautsdefrance.fr\/blog\/wp-content\/uploads\/2026\/07\/IMG_1753-scaled.jpeg 1920w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\" style=\"font-size:14px\"><strong>-Vous int\u00e9grez l\u2019\u00e9quipe de France de coiffure \u00e0 seulement 16 ans. Comment vit-on une telle exp\u00e9rience \u00e0 cet \u00e2ge ?<br>-RP\u00a0: <\/strong>Je n\u2019ai pas mesur\u00e9 tout cela. Je voulais tout de suite \u00eatre champion du monde, je voulais \u00eatre le meilleur. <br>Mais j&rsquo;\u00e9tais tr\u00e8s jeune et il a fallu s\u2019accrocher\u2026J\u2019ai mont\u00e9 les \u00e9chelons les uns apr\u00e8s les autres. Je garde toutefois un merveilleux souvenir de ce salon qu\u2019avait cr\u00e9\u00e9 mon grand-p\u00e8re dans un ancien garage, repris par mon p\u00e8re et dans lequel j\u2019ai fait mon apprentissage. Je voulais le reprendre ce salon, c\u2019\u00e9tait tout trac\u00e9, je n\u2019avais pas encore les aspirations que j\u2019ai eues par la suite. Je ramenais des titres, mon grand- p\u00e8re \u00e9tait super fier (sourire) et puis quand il a vu que je partais de plus en plus, il m\u2019a incit\u00e9 \u00e0 rester au Mans (o\u00f9 nous vivions), il faut dire que dans ma famille, on craignait l\u2019inconnu (sourire). J\u2019\u00e9tais un peu partag\u00e9 mais j\u2019avais envie de gagner encore plus de m\u00e9dailles, j\u2019\u00e9tais jeune\u2026 Au d\u00e9but, \u00e7a comptait beaucoup et puis j\u2019ai r\u00e9alis\u00e9 que ce n\u2019\u00e9tait pas le plus important. C\u2019est le discours que je tiens aujourd\u2019hui aux jeunes, il ne faut pas \u00eatre press\u00e9 de passer son CAP, son BP, deux ans de brevet, 1 an de BM, etc. Il faut prendre le temps d\u2019apprendre son m\u00e9tier, de se perfectionner. En France, nous avons beaucoup de chance d\u2019avoir ces formations si qualifiantes, il n\u2019y a pas cela aux Etats-Unis, en Chine, etc.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"alignright size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/www.cma-hautsdefrance.fr\/blog\/wp-content\/uploads\/2026\/07\/DSCF2666-HD-1024x682-1.png\" alt=\"\" class=\"wp-image-11163\" style=\"aspect-ratio:1.5014964760402922;width:479px;height:auto\" srcset=\"https:\/\/www.cma-hautsdefrance.fr\/blog\/wp-content\/uploads\/2026\/07\/DSCF2666-HD-1024x682-1.png 1024w, https:\/\/www.cma-hautsdefrance.fr\/blog\/wp-content\/uploads\/2026\/07\/DSCF2666-HD-1024x682-1-300x200.png 300w, https:\/\/www.cma-hautsdefrance.fr\/blog\/wp-content\/uploads\/2026\/07\/DSCF2666-HD-1024x682-1-768x512.png 768w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\" style=\"font-size:14px\"><strong>-\u00c0 18 ans, vous devenez Meilleur Apprenti de France, \u00e0 19 ans, champion de France. Est-ce \u00e0 ce moment-l\u00e0 que vous prenez conscience de votre potentiel ?<br>-RP\u00a0: <\/strong>Non, je ne me rendais pas compte. J\u2019ai \u00e9t\u00e9 champion presque tous les ans, de 16 \u00e0 27 ans\u2026 (rire). J\u2019ai oubli\u00e9 tout le reste, j\u2019aurais pu \u00eatre avec mes copains, sortir, aller m\u2019amuser mais c\u2019\u00e9tait le choix de ma vie. J\u2019\u00e9tais d\u00e9termin\u00e9. Il n\u2019y avait que la r\u00e9ussite qui comptait. Et si aujourd\u2019hui je devais tout refaire, je le referais exactement la m\u00eame chose. Je n\u2019ai absolument aucun regret. Mon obsession, c\u2019\u00e9tait de gagner et de mettre \u00e0 profit ce que j\u2019avais appris. Pour cela, j\u2019ai \u00e9crit cinq livres*o\u00f9 j\u2019\u00e9voque cette m\u00e9thode de travail pour que des jeunes apprennent \u00e0 travailler autrement. Il y a quatorze ans, parmi d&rsquo;autres qui m&rsquo;ont fait confiance, il y eu notamment Laure Bazan (aujourd\u2019hui pr\u00e9sidente de l\u2019UNEC). Je les ai convaincus de l\u2019int\u00e9r\u00eat de ma m\u00e9thode qui est aujourd&rsquo;hui dispens\u00e9e dans plus de 200 \u00e9coles en France, plus de 600 dans le monde, traduite dans 34 pays.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"font-size:18px\"><strong>\u00ab\u00a0Je pense que la coiffure est un vrai terrain d&rsquo;expression artistique\u00a0\u00bb<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"font-size:14px\"><strong>-Vous avez ensuite remport\u00e9 de nombreux titres, jusqu\u2019\u00e0 devenir champion du monde en 2002. Quel regard portez-vous aujourd\u2019hui sur ce parcours exceptionnel ?<br>-RP&nbsp;:<\/strong> Je ressens de la gratitude. En fait, je crois que m\u00eame encore aujourd\u2019hui je ne prends pas conscience de ce que j\u2019ai accompli\u2026Ma famille m\u2019a aid\u00e9 \u00e0 tracer mon chemin et tous ceux que j\u2019ai crois\u00e9 sur ma route. J\u2019ai eu de la chance, j\u2019ai de vrais engagements avec les gens, dans mon travail.<br>&nbsp;Et puis j\u2019aime profond\u00e9ment ce que je fais, j\u2019\u00e9prouve de la passion \u00e0 accomplir tout cela, je m\u2019entoure de bonnes personnes aussi. Ma vie personnelle et ma vie professionnelle sont tr\u00e8s imbriqu\u00e9es en fait. Les rencontres comptent beaucoup, elles m\u2019ont aussi permis de d\u00e9velopper mon travail. C\u2019est ainsi qu\u2019il y a 15 ans j\u2019ai d\u00e9couvert gr\u00e2ce \u00e0 un ami aux Etats Unis, les QR Codes dans les livres de cuisine, je les ai reli\u00e9s \u00e0 mes livrets de formations au Mexique. \u00c7a n\u2019existait pas ailleurs, j\u2019ai innov\u00e9 en proposant les premi\u00e8res vid\u00e9os DVD. J\u2019ai cr\u00e9\u00e9 un simulateur de coupe 3 D afin de comprendre par exemple la g\u00e9om\u00e9trie de coupe\u2026Tout cela ne s\u2019est pas fait tout seul, c\u2019est la somme de rencontres qui l\u2019a permis.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"alignright size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"831\" src=\"https:\/\/www.cma-hautsdefrance.fr\/blog\/wp-content\/uploads\/2026\/07\/IMG_0386-2-1024x831.jpg\" alt=\"\" class=\"wp-image-11162\" style=\"aspect-ratio:1.2322645396439702;width:365px;height:auto\" srcset=\"https:\/\/www.cma-hautsdefrance.fr\/blog\/wp-content\/uploads\/2026\/07\/IMG_0386-2-1024x831.jpg 1024w, https:\/\/www.cma-hautsdefrance.fr\/blog\/wp-content\/uploads\/2026\/07\/IMG_0386-2-300x243.jpg 300w, https:\/\/www.cma-hautsdefrance.fr\/blog\/wp-content\/uploads\/2026\/07\/IMG_0386-2-768x623.jpg 768w, https:\/\/www.cma-hautsdefrance.fr\/blog\/wp-content\/uploads\/2026\/07\/IMG_0386-2.jpg 1284w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\" style=\"font-size:14px\"><strong>-Vous avez travaill\u00e9 sur de grands d\u00e9fil\u00e9s de haute couture, sur des spectacles embl\u00e9matiques tels que Le Roi Soleil, Mozart, l\u2019Op\u00e9ra Rock et m\u00eame des films tels que Jeanne du Barry de Maiwenn. Vous avez \u00e9t\u00e9 aussi le coiffeur officiel des JO et JP 2024\u00a0\u2026 Qu\u2019est-ce qui vous attire dans ces univers artistiques, sportifs &#8230; ?<br>-RP\u00a0: <\/strong>J\u2019adore \u00e7a (rire)\u00a0! Je pense aussi que la formation et l\u2019artistique se compl\u00e8tent parfaitement, cela s\u2019\u00e9quilibre parfaitement dans mes activit\u00e9s. Ce que j\u2019aime c\u2019est de pouvoir raconter une histoire et je pense que la coiffure est un v\u00e9ritable terrain d\u2019expression artistique. J\u2019ai ador\u00e9 m\u2019exprimer \u00e0 travers la com\u00e9die musicale, en plus j\u2019aime beaucoup l\u2019Histoire, \u00e7a m\u2019inspire \u00e9norm\u00e9ment dans mon travail. Je fais beaucoup de recherches, dans les mus\u00e9es, dans les ouvrages historiques, afin de trouver des sources d\u2019inspiration. Avec les r\u00e9seaux, Internet et l\u2019IA c\u2019est tr\u00e8s pratique aussi. J\u2019aime beaucoup cr\u00e9er des personnages, comme celui de Nathalie Portman dans le film The Gallerist (Ndlr : dans les salles fran\u00e7aises courant 2026).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"font-size:14px\"><strong>&#8211; Apr\u00e8s avoir atteint le plus haut niveau, vous avez choisi de cr\u00e9er votre propre organisme de formation. Pourquoi la transmission est-elle devenue une priorit\u00e9 pour vous ?<br>-RP\u00a0: <\/strong>En fait \u00e7a l\u2019a toujours \u00e9t\u00e9 en fait, j\u2019ai mont\u00e9 mon centre de formation \u00e0 25 ans. J\u2019ai \u00e9galement rencontr\u00e9 des personnes qui m\u2019ont appris \u00e0 \u00eatre p\u00e9dagogue. A l\u2019\u00e9poque on demandait d\u2019animer des s\u00e9ances via des entreprises comme L&rsquo;Or\u00e9al, cela m\u2019a beaucoup pr\u00e9par\u00e9 \u00e0 la prise de parole aussi pour d\u00e9livrer le bon message. Donc la transmission est incontournable.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"font-size:14px\"><strong>-Aujourd\u2019hui, votre acad\u00e9mie forme plus de 10 000 coiffeurs chaque ann\u00e9e en France et plus de 30 000 dans le monde. Qu\u2019est-ce qui fait, selon vous, la force de la \u00ab\u00a0formation Rapha\u00ebl Perrier\u00a0\u00bb ?<br>-RP\u00a0: <\/strong>Je crois en fait que les chiffres ne m\u2019importent pas vraiment\u2026 en fait moi ce que j\u2019aime c\u2019est apporter des id\u00e9es innovantes. Nous sommes tr\u00e8s pr\u00e9sents dans les Chambres de M\u00e9tiers et de l&rsquo;Artisanat, les salons, pour les accompagner afin de d\u00e9velopper le m\u00e9tier et notre richesse est l\u00e0. Apporter des id\u00e9es. L\u2019autre force, c\u2019est aussi de tenir compte du m\u00e9lange culturel, des diff\u00e9rences entre chaque pays\u00a0: proposer par exemple de travailler sur les cheveux textur\u00e9s (non lisses) ou \u00e0 l\u2019inverse tr\u00e8s raides, etc. On s\u2019adapte \u00e0 tous les publics et j\u2019ai la chance d\u2019avoir des gens motiv\u00e9s et passionn\u00e9s pour m\u2019accompagner.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"font-size:18px\"><strong>\u00ab\u00a0Il faut garder l&rsquo;envie et l&rsquo;\u00e9tincelle\u00a0\u00bb<\/strong><\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"alignright size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/www.cma-hautsdefrance.fr\/blog\/wp-content\/uploads\/2026\/07\/IMG_1761-1024x768.jpeg\" alt=\"\" class=\"wp-image-11157\" style=\"width:541px;height:auto\" srcset=\"https:\/\/www.cma-hautsdefrance.fr\/blog\/wp-content\/uploads\/2026\/07\/IMG_1761-1024x768.jpeg 1024w, https:\/\/www.cma-hautsdefrance.fr\/blog\/wp-content\/uploads\/2026\/07\/IMG_1761-300x225.jpeg 300w, https:\/\/www.cma-hautsdefrance.fr\/blog\/wp-content\/uploads\/2026\/07\/IMG_1761-768x576.jpeg 768w, https:\/\/www.cma-hautsdefrance.fr\/blog\/wp-content\/uploads\/2026\/07\/IMG_1761-1536x1152.jpeg 1536w, https:\/\/www.cma-hautsdefrance.fr\/blog\/wp-content\/uploads\/2026\/07\/IMG_1761-2048x1536.jpeg 2048w, https:\/\/www.cma-hautsdefrance.fr\/blog\/wp-content\/uploads\/2026\/07\/IMG_1761-760x570.jpeg 760w, https:\/\/www.cma-hautsdefrance.fr\/blog\/wp-content\/uploads\/2026\/07\/IMG_1761-365x274.jpeg 365w, https:\/\/www.cma-hautsdefrance.fr\/blog\/wp-content\/uploads\/2026\/07\/IMG_1761-320x241.jpeg 320w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\" style=\"font-size:14px\"><strong>&#8211; Vous dites vouloir \u00ab <em>faire rayonner le m\u00e9tier de coiffeur et donner aux artisans les cl\u00e9s pour se r\u00e9inventer \u00bb<\/em>. Comment accompagnez-vous les professionnels face aux \u00e9volutions du m\u00e9tier ?<br>-RP\u00a0: <\/strong>Avec ces m\u00e9thodes mais aussi avec un club que nous avons cr\u00e9\u00e9, un v\u00e9ritable r\u00e9seau au quotidien pour les professionnels dans la gestion et le d\u00e9veloppement des salons de coiffure.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"font-size:14px\"><strong>-Aujourd\u2019hui, vous participez \u00e0 deux masterclass \u00e0 la Chambre de M\u00e9tiers et de l\u2019Artisanat des Hauts-de-France, ici \u00e0 Lille, en partenariat avec l\u2019UNEC. Qu\u2019est-ce que cela repr\u00e9sente pour vous de venir partager votre exp\u00e9rience avec les artisans, les professeurs, les apprentis ?<br>-RP\u00a0: <\/strong>J\u2019adore \u00e7a\u00a0! Ce partage d\u2019exp\u00e9riences me permet de revenir \u00e0 la base du m\u00e9tier et quand je me d\u00e9place ce que j\u2019aime aussi ce sont ces rencontres. J\u2019aime entendre ce que les gens ont \u00e0 dire, mais aussi donner (ou parfois m\u00eame recevoir) des conseils.\u00a0 C\u2019est vraiment tr\u00e8s int\u00e9ressant d\u2019avoir ce regard du \u00ab\u00a0terrain\u00a0\u00bb.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/www.cma-hautsdefrance.fr\/blog\/wp-content\/uploads\/2026\/07\/shared-image-91-1024x768.jpg\" alt=\"\" class=\"wp-image-11159\" style=\"width:459px;height:auto\" srcset=\"https:\/\/www.cma-hautsdefrance.fr\/blog\/wp-content\/uploads\/2026\/07\/shared-image-91-1024x768.jpg 1024w, https:\/\/www.cma-hautsdefrance.fr\/blog\/wp-content\/uploads\/2026\/07\/shared-image-91-300x225.jpg 300w, https:\/\/www.cma-hautsdefrance.fr\/blog\/wp-content\/uploads\/2026\/07\/shared-image-91-768x576.jpg 768w, https:\/\/www.cma-hautsdefrance.fr\/blog\/wp-content\/uploads\/2026\/07\/shared-image-91-1536x1152.jpg 1536w, https:\/\/www.cma-hautsdefrance.fr\/blog\/wp-content\/uploads\/2026\/07\/shared-image-91-760x570.jpg 760w, https:\/\/www.cma-hautsdefrance.fr\/blog\/wp-content\/uploads\/2026\/07\/shared-image-91-365x274.jpg 365w, https:\/\/www.cma-hautsdefrance.fr\/blog\/wp-content\/uploads\/2026\/07\/shared-image-91-320x241.jpg 320w, https:\/\/www.cma-hautsdefrance.fr\/blog\/wp-content\/uploads\/2026\/07\/shared-image-91.jpg 2040w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\" style=\"font-size:14px\"><strong>-Comment voyez-vous \u00e9voluer le m\u00e9tier de coiffeur dans les ann\u00e9es \u00e0 venir ?<br>-RP&nbsp;: <\/strong>Je suis tr\u00e8s optimiste. Tout le monde parle de l\u2019IA, certes on peut l\u2019associer \u00e0 notre travail mais il y a aussi l\u2019exp\u00e9rience client qui est fondamentale. Nous pouvons faire vivre des \u00e9motions \u00e0 vos clients. &nbsp;Je propose ainsi une exp\u00e9rience \u00ab&nbsp;m\u00e8re fille&nbsp;\u00bb dans nos salons, elles passent trois heures \u00e0 se faire \u00ab&nbsp;chouchouter&nbsp;\u00bb dans un lieu privatis\u00e9.<br>\u00c7a l\u2019IA ne peut pas le procurer. Donc le coiffeur a encore de belles ann\u00e9es devant lui mais il va quand m\u00eame falloir prendre le virage. Les produits ont beaucoup \u00e9volu\u00e9, on n\u2019est plus oblig\u00e9s de passer par de multiples \u00e9tapes, il y a aussi les produits \u00ab&nbsp;v\u00e9g\u00e9&nbsp;\u00bb, c\u2019est un aspect \u00e9thique int\u00e9ressant. Le \u00ab&nbsp;green&nbsp;\u00bb dans notre m\u00e9tier fait du bien&nbsp;!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"font-size:14px\"><strong>-Quels sont, selon vous, les principaux d\u00e9fis auxquels les jeunes coiffeurs devront faire face ?<br>-RP\u00a0: <\/strong>Je pense qu\u2019ils doivent rester passionn\u00e9s. Beaucoup de gens ne vont plus vers les m\u00e9tiers de l\u2019artisanat parce qu\u2019ils pensent que c\u2019est trop dur donc c\u2019est \u00e0 nous de leur montrer tout ce qu\u2019il est possible de faire gr\u00e2ce \u00e0 la formation. Avec la passion on peut tout faire, je veux aussi leur d\u00e9montrer cela. Il faut garder l\u2019envie et l\u2019\u00e9tincelle. Et rester fid\u00e8le \u00e0 ce qu\u2019on est. On doute toujours mais quand on reste fid\u00e8le \u00e0 sa ligne de conduite, \u00e7a marche. Le travail et la passion sont les cl\u00e9s de la r\u00e9ussite.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"font-size:14px\"><em>Cr\u00e9dit photos CMA HDF<\/em> <em>&amp; RP<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"font-size:14px\">*Nomm\u00e9 Meilleur Apprenti de France \u00e0 18 ans, Rapha\u00ebl Perrier encha\u00eene les victoires avec les titres de champion de France, champion d\u2019Europe et son premier sacre de champion du Monde en 2002. En 2010, il remporte deux nouveaux titres de Champion du Monde, en individuel et en \u00e9quipe. Il prend la pr\u00e9sidence de l\u2019\u00c9quipe de France de coiffure en 2011, et entra\u00eene aujourd\u2019hui la nouvelle g\u00e9n\u00e9ration de comp\u00e9titeurs. En 2012, il ouvre son premier salon de coiffure \u00e0 Paris. S\u2019ensuit l\u2019ouverture de salons en province et \u00e0 l\u2019international, avec notamment 9 salons en Chine. En 2014, il cr\u00e9e un concept d\u2019apprentissage in\u00e9dit et interactif, PI BY RP, d\u00e9clin\u00e9 en 5 manuels. En 2015, \u00a0il ouvre le premier atelier fran\u00e7ais A&amp;R d\u00e9di\u00e9 \u00e0 la cr\u00e9ation de chevelures pour le monde du spectacle. <br>En 2016, Rapha\u00ebl Perrier lance son Club, avec pour ambition de f\u00e9d\u00e9rer des professionnels de la coiffure. Parall\u00e8lement \u00e0 son d\u00e9veloppement en France et dans le monde entier, il a \u00e9galement cr\u00e9\u00e9 en 2023 un nouveau concept Me&amp;My Salon pour aider les entreprises \u00e0 se moderniser et se renouveler. (Sources site officiel Rapha\u00ebl Perrier)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"font-size:14px\">*L&rsquo;UNEC HDF :  L&rsquo;antenne Hauts de France de l&rsquo;Union Nationale des Entreprises de Coiffure est pr\u00e9sid\u00e9e par Madame Laure Bazan.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"font-size:14px\"><\/p>\n\n\n","protected":false},"excerpt":{"rendered":"<p><span class=\"span-reading-time rt-reading-time\" style=\"display: block;\"><span class=\"rt-label rt-prefix\">Temps de lecture\u00a0: <\/span> <span class=\"rt-time\"> 8<\/span> <span class=\"rt-label rt-postfix\">minutes<\/span><\/span>Si son visage est moins connu du grand public, son nom est une v\u00e9ritable r\u00e9f\u00e9rence &hellip; <\/p>\n","protected":false},"author":20,"featured_media":11149,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[28,6,57,109],"tags":[71,73,158,79,68,63,91,334,335],"class_list":["post-11144","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actu-nord","category-actualites","category-ateliers-des-savoirs","category-linvite","tag-artisan","tag-artisanat","tag-cma-hdf","tag-coiffure","tag-formation","tag-hauts-de-france","tag-interview","tag-raphael-perrier","tag-unec"],"_links":{"self":[{"href":"https:\/\/www.cma-hautsdefrance.fr\/blog\/wp-json\/wp\/v2\/posts\/11144","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cma-hautsdefrance.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cma-hautsdefrance.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cma-hautsdefrance.fr\/blog\/wp-json\/wp\/v2\/users\/20"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cma-hautsdefrance.fr\/blog\/wp-json\/wp\/v2\/comments?post=11144"}],"version-history":[{"count":15,"href":"https:\/\/www.cma-hautsdefrance.fr\/blog\/wp-json\/wp\/v2\/posts\/11144\/revisions"}],"predecessor-version":[{"id":11168,"href":"https:\/\/www.cma-hautsdefrance.fr\/blog\/wp-json\/wp\/v2\/posts\/11144\/revisions\/11168"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cma-hautsdefrance.fr\/blog\/wp-json\/wp\/v2\/media\/11149"}],"wp:attachment":[{"href":"https:\/\/www.cma-hautsdefrance.fr\/blog\/wp-json\/wp\/v2\/media?parent=11144"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cma-hautsdefrance.fr\/blog\/wp-json\/wp\/v2\/categories?post=11144"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cma-hautsdefrance.fr\/blog\/wp-json\/wp\/v2\/tags?post=11144"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}